{"id":921,"date":"2016-05-04T01:30:50","date_gmt":"2016-05-04T01:30:50","guid":{"rendered":"http:\/\/cristozzo.com.br\/blog\/?p=921"},"modified":"2016-05-05T11:52:07","modified_gmt":"2016-05-05T11:52:07","slug":"curso-de-risotos-e-sopas","status":"publish","type":"post","link":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/","title":{"rendered":"Curso de Risotos e Sopas Funcionais 12\/05"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><a href=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo1.png\" alt=\"Curso Risotos e Sopas Cris Tozzo\" width=\"500\" height=\"500\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>O friozinho est&aacute; chegando e, nesse clima gostoso,&nbsp;nada melhor do que optar por&nbsp;refei&ccedil;&otilde;es saborosas e quentinhas. Por isso resolvi preparar para voc&ecirc;s um Curso de Gastronomia Funcional s&oacute; com receitas de Risotos e Sopas!<\/p>\n<p>Separei para esse curso as receitas mais gostosas de risotos e sopas funcionais para mostrar como &eacute; poss&iacute;vel incluir essas del&iacute;cias no card&aacute;pio sem fugir da dieta.&nbsp;N&atilde;o h&aacute; pr&eacute;-requisitos para participa&ccedil;&atilde;o, &eacute; aberto ao p&uacute;blico leigo e tamb&eacute;m aos profissionais.<\/p>\n<p>O Curso ser&aacute; realizado no dia&nbsp;<b>12\/05&nbsp;(quinta-feira),&nbsp;das 19h30 &agrave;s 22h30, em Florian&oacute;polis.<\/b><\/p>\n<p>Todas as prepara&ccedil;&otilde;es ser&atilde;o #SEMGL&Uacute;TEN #SEMLACTOSE #BAIXO&Iacute;NDICEGLIC&Ecirc;MICO e tamb&eacute;m inclui op&ccedil;&atilde;o de receitas para veganos ou al&eacute;rgicos.<\/p>\n<p>&nbsp;<\/p>\n<p><em>* todos os alunos receber&atilde;o um livreto com as receitas, orienta&ccedil;&otilde;es e um certificado de participa&ccedil;&atilde;o<\/em><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>Neste curso voc&ecirc; vai aprender:<\/strong><\/p>\n<p>Sopa Creme Alcalinizante<\/p>\n<p>Sopa Detox de Lentilhas<\/p>\n<p>Caldo caseiro<\/p>\n<p>Base para risotos Funcionais<\/p>\n<p>Risoto Cremoso de Arroz Negro com Camar&otilde;es<\/p>\n<p>Risoto ao Pesto com Tomates Confitados<\/p>\n<p>Risoto Vegano de Abacaxi com Nozes Caramelizadas<\/p>\n<p>Receitas Surpresas para varia&ccedil;&otilde;es!<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>IMPORTANTE!&nbsp;<\/u><\/strong><\/p>\n<p>As vagas s&atilde;o limitadas.&nbsp;A confirma&ccedil;&atilde;o da inscri&ccedil;&atilde;o &eacute; feita mediante dep&oacute;sito banc&aacute;rio e&nbsp;comprovante enviado para o e-mail cursos@cristozzo.com.br<\/p>\n<p>Para garantir a sua vaga a inscri&ccedil;&atilde;o &eacute; feita por dep&oacute;sito\/transfer&ecirc;ncia em conta no&nbsp;<strong>BANCO DO BRASIL.&nbsp;<\/strong>Voc&ecirc;&nbsp;deve enviar o comprovante de dep&oacute;sito como anexo para este mesmo email, al&eacute;m do seu nome completo e telefone para que possamos efetivar a sua inscri&ccedil;&atilde;o, preparar o material e emitir o certificado.<\/p>\n<p>&nbsp;<\/p>\n<p>As inscri&ccedil;&otilde;es com desconto custam&nbsp;<b>R$150,00 at&eacute; dia 09\/05 (segunda-feira) e 180,00 a partir do dia 10\/05 (ter&ccedil;a-feira)<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>Dados para dep&oacute;sito ou transfer&ecirc;ncia:<\/p>\n<p><strong>Banco do Brasil:<\/strong><\/p>\n<p>Ag&ecirc;ncia: 3616-1.<\/p>\n<p>Conta Corrente: 13.577-1<\/p>\n<p>&nbsp;<\/p>\n<p>Aguardo por voc&ecirc;s!<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><strong>O QU&Ecirc;?<\/strong><\/span> Curso Risotos e Sopas Funcionais<\/p>\n<p><strong>ONDE?<\/strong> Florian&oacute;polis &ndash; Espa&ccedil;o Carlos Wagner &ndash;&nbsp;R. Ver. Frederico Veras, 384 &ndash; Pantanal, Florian&oacute;polis &ndash; SC, 88040-200<\/p>\n<p><strong>QUANDO?<\/strong> 12 de maio de 2016 (quinta-feira) das 19h30 &agrave;s 22h30<\/p>\n<p><strong>QUANTO?<\/strong> R$ 150,00 at&eacute; dia 09\/05 (segunda-feira) e R$ 180,00 a partir do dia 10\/05 (ter&ccedil;a-feira)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O friozinho est&aacute; chegando e, nesse clima gostoso,&nbsp;nada melhor do que optar por&nbsp;refei&ccedil;&otilde;es saborosas e quentinhas. Por isso resolvi preparar para voc&ecirc;s um Curso de Gastronomia Funcional s&oacute; com receitas de Risotos e Sopas! Separei para esse curso as receitas mais gostosas de risotos e sopas funcionais para mostrar como &eacute; poss&iacute;vel incluir essas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,4],"tags":[226,239],"class_list":["post-921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-eventos","tag-alimentacaosaudavel","tag-gastronomiafuncional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog<\/title>\n<meta name=\"description\" content=\"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"og:description\" content=\"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/\" \/>\n<meta property=\"og:site_name\" content=\"Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristozzonutri\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-04T01:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-05T11:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"conteudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/cristozzonutri\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"conteudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/\",\"name\":\"Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog\",\"isPartOf\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png\",\"datePublished\":\"2016-05-04T01:30:50+00:00\",\"dateModified\":\"2016-05-05T11:52:07+00:00\",\"author\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\"},\"description\":\"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.\",\"breadcrumb\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png\",\"contentUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png\",\"width\":696,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/cristozzo.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso de Risotos e Sopas Funcionais 12\/05\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/\",\"name\":\"Cris Tozzo Nutricionista Blog\",\"description\":\"Cris Tozzo Nutricionista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\",\"name\":\"conteudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"caption\":\"conteudo\"},\"sameAs\":[\"http:\/\/www.cristozzo.com.br\",\"https:\/\/www.facebook.com\/cristozzonutri\",\"https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri\"],\"url\":\"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog","description":"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog","og_description":"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.","og_url":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/","og_site_name":"Cris Tozzo Nutricionista Blog","article_author":"https:\/\/www.facebook.com\/cristozzonutri","article_published_time":"2016-05-04T01:30:50+00:00","article_modified_time":"2016-05-05T11:52:07+00:00","og_image":[{"width":696,"height":507,"url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png","type":"image\/png"}],"author":"conteudo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/cristozzonutri","twitter_misc":{"Written by":"conteudo","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/","url":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/","name":"Curso de Risotos e Sopas Funcionais 12\/05 - Cris Tozzo Nutricionista Blog","isPartOf":{"@id":"http:\/\/cristozzo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage"},"image":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage"},"thumbnailUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png","datePublished":"2016-05-04T01:30:50+00:00","dateModified":"2016-05-05T11:52:07+00:00","author":{"@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a"},"description":"O Curso ser\u00e1 realizado no dia 12\/05 (quinta-feira), das 19h30 \u00e0s 22h30, em Florian\u00f3polis.","breadcrumb":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#primaryimage","url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png","contentUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/05\/Curso-Risotos-e-Sopas-Cris-Tozzo-e1462414823127.png","width":696,"height":507},{"@type":"BreadcrumbList","@id":"http:\/\/cristozzo.com.br\/blog\/curso-de-risotos-e-sopas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/cristozzo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Curso de Risotos e Sopas Funcionais 12\/05"}]},{"@type":"WebSite","@id":"http:\/\/cristozzo.com.br\/blog\/#website","url":"http:\/\/cristozzo.com.br\/blog\/","name":"Cris Tozzo Nutricionista Blog","description":"Cris Tozzo Nutricionista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a","name":"conteudo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","caption":"conteudo"},"sameAs":["http:\/\/www.cristozzo.com.br","https:\/\/www.facebook.com\/cristozzonutri","https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri"],"url":"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/"}]}},"_links":{"self":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=921"}],"version-history":[{"count":7,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/921\/revisions"}],"predecessor-version":[{"id":934,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/921\/revisions\/934"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media\/922"}],"wp:attachment":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=921"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}