{"id":728,"date":"2015-12-09T17:24:16","date_gmt":"2015-12-09T17:24:16","guid":{"rendered":"http:\/\/cristozzo.com.br\/blog\/?p=728"},"modified":"2015-12-09T17:24:16","modified_gmt":"2015-12-09T17:24:16","slug":"candidiase-como-a-alimentacao-pode-combater-o-problema","status":"publish","type":"post","link":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/","title":{"rendered":"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema!"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><a href=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID%C3%8DASE-61.png\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID%C3%8DASE-61.png\" alt=\"CANDID&Iacute;ASE-6\" width=\"750\" height=\"480\" \/><\/a><\/p>\n<p>Que mulher nunca teve candid&iacute;ase? A doen&ccedil;a &eacute; um dos problemas femininos mais comuns e que, infelizmente, cada uma de n&oacute;s ter&aacute; ao menos uma vez na vida. A <em>Candida Albicans <\/em>&eacute; o principal fungo causador de infec&ccedil;&atilde;o vaginal, que quando associado &agrave; baixa imunidade e calor causa infec&ccedil;&atilde;o. Provoca geralmente coceira nas partes &iacute;ntimas, acompanhadas de ardor e corrimento esbranqui&ccedil;ado. Desconforto e incomodo na certa! Mas o que muita gente n&atilde;o sabe &eacute; que outros sintomas n&atilde;o t&atilde;o espec&iacute;ficos podem estar relacionados a um aumento na prolifera&ccedil;&atilde;o de Candida pertinho dali, no seu intestino, como falta de energia, baixa imunidade, alta produ&ccedil;&atilde;o de gases intestinais, altern&acirc;ncia na consist&ecirc;ncia das fezes, acne no adulto, fungos nas unhas e coceiras de pele. Esses sintomas aparecem quando o fungo (que habita normalmente nossa flora intestinal) se prolifera em alta quantidade, atacando nossos tecidos e comprometendo principalmente nossa imunidade e energia corporal.<\/p>\n<p>N&atilde;o se desespere se voc&ecirc; identificou-se com os sintomas, pois a&nbsp;desordem normalmente se manifesta quando estamos com a alimenta&ccedil;&atilde;o e os h&aacute;bitos de vida desregrados, dormindo pouco, estressando-se muito e comendo alimentos que comprometem a sa&uacute;de do nosso intestino.<\/p>\n<p>Para ficar longe da candid&iacute;ase algumas mudan&ccedil;as na&nbsp;alimenta&ccedil;&atilde;o s&atilde;o necess&aacute;rias, muita gente n&atilde;o sabe, mas a m&aacute; nutri&ccedil;&atilde;o desequilibra a flora intestinal e favorece o aparecimento da inimiga, tanto causando infec&ccedil;&otilde;es vaginais como oportunistas, podendo inclusive tornar o problema frequente, as chamadas &ldquo;c&acirc;ndidas de repeti&ccedil;&atilde;o&rdquo;.<\/p>\n<p>Sabendo que o que voc&ecirc; come pode influenciar muito nessa doen&ccedil;a, nada mais justo que cuidar de si e tirar do card&aacute;pio o que pode aumentar a prolifera&ccedil;&atilde;o dos fungos. Dormir bem e relaxar s&atilde;o atitudes muito importantes, mas o foco principal na dieta ser&aacute; aumentar o sistema imune, melhorar a microbiota intestinal e diminuir a prolifera&ccedil;&atilde;o f&uacute;ngica no organismo. Para isso um conjunto de dieta adequada e suplementa&ccedil;&atilde;o ser&atilde;o necess&aacute;rios.<\/p>\n<p>Conhe&ccedil;a as principais dicas para evitar os quadros repetidos de infec&ccedil;&atilde;o e o aumento de candida no intestino:<\/p>\n<p><strong>1 &ndash; Fique longe dos doces:<\/strong><\/p>\n<p>N&atilde;o tem jeito, para ficar longe da candid&iacute;ase &eacute; preciso restringir os doces. Fungos e bact&eacute;rias patog&ecirc;nicas alimentam-se de a&ccedil;&uacute;car, al&eacute;m de alterar o ph intestinal e vaginal favorecendo a prolifera&ccedil;&atilde;o de fungos. Quanto mais prolifera&ccedil;&atilde;o de fungos voc&ecirc; tiver no organismo mais vontade por doces vai sentir, pois os &ldquo;espertinhos&rdquo; liberam subst&acirc;ncias durante a digest&atilde;o para garantir a sobreviv&ecirc;ncia deles. Portanto, pra quem apresenta o quadro de repeti&ccedil;&atilde;o da doen&ccedil;a precisa ficar longe de a&ccedil;&uacute;car, farinhas refinadas, mel, melado, refrigerantes, balas, doces em geral e industrializados ado&ccedil;ados.<\/p>\n<p><strong>2 &ndash; Nem fruta esta liberada<\/strong><\/p>\n<p>As frutas, se consumidas em excesso, podem ser prejudiciais por conterem uma grande quantidade de frutose, que eleva a glicemia e pode piorar o problema. Os sucos (sendo naturais ou n&atilde;o) cont&eacute;m grande quantidade de frutose e devem ser evitados, assim como caldo de cana e xarope de milho, presentes em muitos produtos industrializados. Frutas secas e oleaginosas tamb&eacute;m devem ser evitadas, o modo de armazenamento da maioria delas favorece a prolifera&ccedil;&atilde;o de fungos. Isso n&atilde;o quer dizer que voc&ecirc; deve riscar frutas do card&aacute;pio, muito pelo contr&aacute;rio, elas ser&atilde;o importantes para fornecer vitaminas e minerais adequados para melhora do sistema imune. A regra aqui &eacute;: Prefira as frutas frescas e inteiras! Consuma cerca de 3 a 5 por&ccedil;&otilde;es ao dia para garantir a ingest&atilde;o&nbsp;adequada de nutrientes, e preferencialmente distribu&iacute;das ao longo do dia.<\/p>\n<p><strong>3- Fique longe dos fermentados<\/strong><\/p>\n<p>Alimentos e bebidas que s&atilde;o fermentadas pela a&ccedil;&atilde;o de fungos, como o fermento biol&oacute;gico, estimulam o crescimento f&uacute;ngico e desequilibram os microrganismos que vivem naturalmente em nosso intestino. Portanto durante os epis&oacute;dios de c&acirc;ndida voc&ecirc; deve evitar p&atilde;es e massas, vinhos, vinagres, cervejas, queijo gorgonzola, produtos embutidos e todos os tipos de cogumelos.<\/p>\n<p><strong>4&nbsp;&ndash; Ingira alimentos antif&uacute;ngicos<\/strong><\/p>\n<p>Alguns alimentos possuem a&ccedil;&atilde;o antif&uacute;ngica e podem contribuir para a diminui&ccedil;&atilde;o desses microrganismos no seu corpo, como o alho, or&eacute;gano, alecrim, tomilho e sementes de ab&oacute;bora. Outros grandes aliados s&atilde;o os &oacute;leos extra virgens, particularmente o &oacute;leo de coco e o &oacute;leo de or&eacute;gano. Canela &eacute; outra especiaria que aparece com frequ&ecirc;ncia nos artigos cient&iacute;ficos com a&ccedil;&atilde;o antif&uacute;ngica significativa. Voc&ecirc; precisar&aacute; fazer uso di&aacute;rio desses alimentos para garantir a a&ccedil;&atilde;o desejada, portanto abuse dos temperos acima, consuma as sementes de ab&oacute;bora no lanche da manh&atilde; e inclua at&eacute; duas colheres dos &oacute;leos citados nas saladas. Em meu e-book Cozinha Funcional, ensino temperos e &oacute;leos com a&ccedil;&atilde;o antif&uacute;ngica que podem trazer mais sa&uacute;de para os seus pratos acrescentando sempre um toque especial de sabor.<\/p>\n<p>Lembre-se que seu sistema imunol&oacute;gico tamb&eacute;m precisa estar refor&ccedil;ado e cuidados com o intestino ser&atilde;o essenciais, portanto procure um nutricionista que possa lhe ajudar a cuidar desse &oacute;rg&atilde;o. O profissional tamb&eacute;m poder&aacute; lhe prescrever probi&oacute;ticos e fitoter&aacute;picos espec&iacute;ficos que diminuem a prolifera&ccedil;&atilde;o de fungos e melhoram esse sistema. Tratar o problema com medica&ccedil;&atilde;o frequente pode acabar com o sintoma no momento, mas n&atilde;o trata a causa do problema, podendo ainda prejudicar ainda mais a sa&uacute;de do seu intestino e seu sistema imunol&oacute;gico. A terapia conjunta com alimenta&ccedil;&atilde;o pode ser a mudan&ccedil;a necess&aacute;ria que seu corpo precisa para acabar com o sofrimento.&nbsp;&nbsp;N&atilde;o deixe a candid&iacute;ase estragar o seu humor e sa&uacute;de, melhore suas escolhas e pare hoje de alimentar essa inimiga!<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>Que mulher nunca teve candid&iacute;ase? A doen&ccedil;a &eacute; um dos problemas femininos mais comuns e que, infelizmente, cada uma de n&oacute;s ter&aacute; ao menos uma vez na vida. A Candida Albicans &eacute; o principal fungo causador de infec&ccedil;&atilde;o vaginal, que quando associado &agrave; baixa imunidade e calor causa infec&ccedil;&atilde;o. Provoca geralmente coceira nas partes &iacute;ntimas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,5],"tags":[194,196,195,187,197],"class_list":["post-728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-destaque","tag-candidiase","tag-cristozzoblog","tag-cristozzonutri","tag-nutricaofuncional","tag-saudedamulher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog<\/title>\n<meta name=\"description\" content=\"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"og:description\" content=\"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/\" \/>\n<meta property=\"og:site_name\" content=\"Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristozzonutri\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-09T17:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"conteudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/cristozzonutri\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"conteudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/\",\"name\":\"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog\",\"isPartOf\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png\",\"datePublished\":\"2015-12-09T17:24:16+00:00\",\"dateModified\":\"2015-12-09T17:24:16+00:00\",\"author\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\"},\"description\":\"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.\",\"breadcrumb\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png\",\"contentUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png\",\"width\":750,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/cristozzo.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/\",\"name\":\"Cris Tozzo Nutricionista Blog\",\"description\":\"Cris Tozzo Nutricionista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\",\"name\":\"conteudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"caption\":\"conteudo\"},\"sameAs\":[\"http:\/\/www.cristozzo.com.br\",\"https:\/\/www.facebook.com\/cristozzonutri\",\"https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri\"],\"url\":\"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog","description":"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog","og_description":"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.","og_url":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/","og_site_name":"Cris Tozzo Nutricionista Blog","article_author":"https:\/\/www.facebook.com\/cristozzonutri","article_published_time":"2015-12-09T17:24:16+00:00","og_image":[{"width":750,"height":480,"url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png","type":"image\/png"}],"author":"conteudo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/cristozzonutri","twitter_misc":{"Written by":"conteudo","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/","url":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/","name":"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema! - Cris Tozzo Nutricionista Blog","isPartOf":{"@id":"http:\/\/cristozzo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage"},"image":{"@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage"},"thumbnailUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png","datePublished":"2015-12-09T17:24:16+00:00","dateModified":"2015-12-09T17:24:16+00:00","author":{"@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a"},"description":"Que mulher nunca teve candid\u00edase? A doen\u00e7a \u00e9 um dos problemas femininos mais comuns e que, infelizmente, cada uma de n\u00f3s ter\u00e1 ao menos uma vez na vida.","breadcrumb":{"@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#primaryimage","url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png","contentUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/12\/CANDID\u00cdASE-61.png","width":750,"height":480},{"@type":"BreadcrumbList","@id":"http:\/\/cristozzo.com.br\/blog\/candidiase-como-a-alimentacao-pode-combater-o-problema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/cristozzo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Candid\u00edase: como a alimenta\u00e7\u00e3o pode combater o problema!"}]},{"@type":"WebSite","@id":"http:\/\/cristozzo.com.br\/blog\/#website","url":"http:\/\/cristozzo.com.br\/blog\/","name":"Cris Tozzo Nutricionista Blog","description":"Cris Tozzo Nutricionista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a","name":"conteudo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","caption":"conteudo"},"sameAs":["http:\/\/www.cristozzo.com.br","https:\/\/www.facebook.com\/cristozzonutri","https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri"],"url":"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/"}]}},"_links":{"self":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":2,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"predecessor-version":[{"id":732,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/728\/revisions\/732"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media\/731"}],"wp:attachment":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}