{"id":682,"date":"2015-11-18T11:56:06","date_gmt":"2015-11-18T11:56:06","guid":{"rendered":"http:\/\/cristozzo.com.br\/blog\/?p=682"},"modified":"2016-12-12T18:08:04","modified_gmt":"2016-12-12T18:08:04","slug":"cabelos-vs-dieta","status":"publish","type":"post","link":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/","title":{"rendered":"Cabelos X Dieta!"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><a href=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri%C3%A7%C3%A3o-para-cabelos-lindos.png\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri%C3%A7%C3%A3o-para-cabelos-lindos.png\" alt=\"Nutri&ccedil;&atilde;o para cabelos lindos\" width=\"700\" height=\"366\" \/><\/a><\/p>\n<p>Cabelo x Dieta<\/p>\n<p>Voc&ecirc; est&aacute; feliz com a sa&uacute;de e apar&ecirc;ncia dos seus cabelos? Ali&aacute;s&hellip; quanto dinheiro j&aacute; gastamos para deixar nossos cabelos lindos? Eis um ponto cr&iacute;tico da nossa vaidade, queremos fios brilhantes, male&aacute;veis e sem queda, dignos de uma propaganda de shampoo. Queda de cabelo e cabelos fracos e quebradi&ccedil;os s&atilde;o reclama&ccedil;&otilde;es frequentes em meu consult&oacute;rio, por isso hoje resolvi falar um pouco sobre a influ&ecirc;ncia da alimenta&ccedil;&atilde;o na sa&uacute;de do seus fios.<\/p>\n<p><!--more--><\/p>\n<p>O&nbsp; cabelo &eacute; constitu&iacute;do de c&eacute;lulas queratinizadas produzida pelo fol&iacute;culo piloso e que se projetam&nbsp; na superf&iacute;cie da epiderme, essas c&eacute;lulas sofrem profunda influ&ecirc;ncia de fatores externos como uso de produtos qu&iacute;micos e exposi&ccedil;&atilde;o solar e fatores internos como horm&ocirc;nios e qualidade da dieta. &Eacute; neste quesito que uma dieta equilibrada e o uso de nutrientes espec&iacute;ficos pode transformar a apar&ecirc;ncia dos seus fios.<\/p>\n<p>Meu primeiro recado &eacute;: quem quer ter resultado nos fios e deixa-los lindos precisar&aacute; de paci&ecirc;ncia. Para garantir que todos os nutrientes necess&aacute;rios &agrave; sa&uacute;de do fio cheguem ao local destinado, e causem aquele &ldquo;efeito de sal&atilde;o&rdquo;, os cuidados dever&atilde;o durar no m&iacute;nimo 3 meses, seja por dieta ou suplementa&ccedil;&atilde;o. Percebo muita ansiedade por parte dos pacientes que querem ver o resultado r&aacute;pido, j&aacute; nos primeiros 30 dias, e muitas vezes desistem do tratamento sem esperar o tempo necess&aacute;rio para a recupera&ccedil;&atilde;o da sa&uacute;de capilar.<\/p>\n<p>Portanto, as mudan&ccedil;as na sua dieta devem come&ccedil;ar hoje. Separei para voc&ecirc;s os principais nutrientes e alimentos que uso em consult&oacute;rio quando a reclama&ccedil;&atilde;o principal &eacute; cabelo, e que observo melhores resultados. Se quer cabelos deslumbrantes e com sa&uacute;de, esses nutrientes ser&atilde;o essenciais e os alimentos fonte n&atilde;o podem ficar de fora do seu card&aacute;pio, confira o que voc&ecirc; precisa incluir para crescimento, brilho e vitalidade dos seus fios:<\/p>\n<p><strong>1 &ndash; Amino&aacute;cidos:<\/strong><\/p>\n<p>A estrutura b&aacute;sica do nosso cabelo &eacute; feita de queratina, uma prote&iacute;na que para ser formada precisa de amino&aacute;cidos como a ciste&iacute;na e a cistina. Para garantir a for&ccedil;a do fio voc&ecirc; precisa da ingest&atilde;o adequada desses componentes, ingira diariamente: <strong>ovos, carnes magras, peixes, latic&iacute;nios, feij&otilde;es e lentilhas. <\/strong><\/p>\n<p><strong>2 &ndash; Vitaminas do complexo B <\/strong><\/p>\n<p>A falta de algumas vitaminas do complexo B altera a fase de crescimento dos fios, aumentando a dura&ccedil;&atilde;o do per&iacute;odo de queda. N&atilde;o poder&atilde;o faltar na sua dieta vitaminas como a biotina, a niacina e a tiamina, al&eacute;m de todo o complexo B. Portanto ingira diariamente: <strong>nozes e semente de girassol (acrescente a frutas picadas como mel&atilde;o e laranja); incremente a salada com repolho e agri&atilde;o e n&atilde;o esque&ccedil;a da aveia e arroz integral.<\/strong><\/p>\n<p><strong>3- Vitamina A:<\/strong><\/p>\n<p>Importante para o crescimento e manuten&ccedil;&atilde;o das c&eacute;lulas do couro cabeludo. Voc&ecirc; encontra na <strong>acelga, cenoura, mam&atilde;o e ab&oacute;bora<\/strong>.<\/p>\n<p><strong>4 &ndash; &Aacute;cidos Graxos<\/strong><\/p>\n<p>Para dar brilho aos cabelos precisamos melhorar suas cut&iacute;culas que s&atilde;o compostas de ceramidas, os nutrientes que d&atilde;o origem a essa estrutura s&atilde;o o &ocirc;mega-3 e o &ocirc;mega-6. Portanto troque os seus &oacute;leos em casa por <strong>&oacute;leos vegetais de amendoim, linha&ccedil;a e girassol. Invista nos peixes e consuma tamb&eacute;m, alternadamente, am&ecirc;ndoas e abacate toda semana<\/strong>.<\/p>\n<p><strong>5 &ndash; Col&aacute;geno e Sil&iacute;cio Org&acirc;nicos<\/strong><\/p>\n<p>O tecido que reveste a parte de baixo do cabelo e ajuda na maleabilidade do fol&iacute;culo piloso &eacute; feito de col&aacute;geno, que pode ser estimulado pela ingest&atilde;o de <strong>pept&iacute;deos de col&aacute;geno<\/strong> e de <strong>sil&iacute;cio org&acirc;nico<\/strong>. Para isso precisamos recorrer &agrave; suplementa&ccedil;&atilde;o, tanto de sil&iacute;cio quanto de col&aacute;geno devem ser prescritos em dosagem e forma farmac&ecirc;utica adequada. Quando em p&oacute;, o col&aacute;geno ou os pept&iacute;deos podem ser adicionados a sucos ou vitaminas, e devem ser consumidos longe de refei&ccedil;&otilde;es que contenham prote&iacute;nas. &nbsp;Sugiro aos meus pacientes a ingest&atilde;o em um dos lanches, da manh&atilde; ou da tarde. J&aacute; o sil&iacute;cio, entra em conjunto com outros nutrientes na suplementa&ccedil;&atilde;o e &eacute; essencial para melhora do brilho, hidrata&ccedil;&atilde;o e elasticidade do fio. Estudo publicado na <em><a href=\"http:\/\/link.springer.com\/journal\/403\">Archives of Dermatological Research<\/a><\/em>, em 2007, avaliou 48 mulheres com cabelos finos e demonstrou que a suplementa&ccedil;&atilde;o de 10mg de sil&iacute;cio org&acirc;nico por 9 meses foi capaz de melhorar a resist&ecirc;ncia a tra&ccedil;&atilde;o, elasticidade e quebra, resultando em um fio mais grosso e resitentente.<\/p>\n<p>Com todos esses nutrientes em &oacute;timo estado no corpo seu cabelo ser&aacute; digno de propaganda de shampoo, no entanto, se estiver perdendo cabelo, as causas podem ser hormonais ou decorrente de defici&ecirc;ncias espec&iacute;ficas, como a falta de ferro, c&aacute;lcio, pot&aacute;ssio e vitamina B6. Voc&ecirc; pode ainda estar com uma produ&ccedil;&atilde;o excessiva de oleosidade no couro cabeludo, o que aumenta a queda e dificulta o crescimento. &Eacute; importante procurar um profissional nutricionista ou m&eacute;dico que possa identificar essas car&ecirc;ncias e excessos e lhe indicar o tratamento adequado para o seu caso.<\/p>\n<p>A dica extra &eacute; pra quem n&atilde;o tem problemas de oleosidade: ingira <strong>1 colher de &oacute;leo de coco extra virgem por dia<\/strong> para deixar os cabelos bonitos e brilhantes e de quebra melhorar a hidrata&ccedil;&atilde;o da pele. Eu adoro usar o &oacute;leo de coco tamb&eacute;m nas pontas (recebi essa dica da minha dermatologista e amei) uso bem pouca quantidade (1 colher de cafezinho) espalhada na m&atilde;o e distribu&iacute;da somente nas pontinhas na hora do banho, antes do &uacute;ltimo enxague. Adoro o fato de n&atilde;o ter nenhum produto qu&iacute;mico associado e mesmo assim deixar meu cabelo mais hidratado e brilhante.<\/p>\n<p>E voc&ecirc;s? O que fazem por cabelos mais lindos? Compartilhem suas dicas e d&uacute;vidas nos coment&aacute;rios!<\/p>\n<p><strong>&nbsp;Cabelo x Dieta<\/strong><\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>Cabelo x Dieta Voc&ecirc; est&aacute; feliz com a sa&uacute;de e apar&ecirc;ncia dos seus cabelos? Ali&aacute;s&hellip; quanto dinheiro j&aacute; gastamos para deixar nossos cabelos lindos? Eis um ponto cr&iacute;tico da nossa vaidade, queremos fios brilhantes, male&aacute;veis e sem queda, dignos de uma propaganda de shampoo. Queda de cabelo e cabelos fracos e quebradi&ccedil;os s&atilde;o reclama&ccedil;&otilde;es frequentes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[291,292,189,23,19,193,190,192,191],"class_list":["post-682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-cabelos","tag-nutricaocapilar","tag-cabelos-lindos","tag-cris-tozzo","tag-funcional","tag-hair","tag-nutricao-de-cabelos","tag-nutricao-e-estetica","tag-saude-da-mulher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cabelos X Dieta! - Cris Tozzo Nutricionista Blog<\/title>\n<meta name=\"description\" content=\"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cabelos X Dieta! - Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"og:description\" content=\"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/\" \/>\n<meta property=\"og:site_name\" content=\"Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristozzonutri\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-18T11:56:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-12T18:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"conteudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/cristozzonutri\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conteudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/\",\"name\":\"Cabelos X Dieta! - Cris Tozzo Nutricionista Blog\",\"isPartOf\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png\",\"datePublished\":\"2015-11-18T11:56:06+00:00\",\"dateModified\":\"2016-12-12T18:08:04+00:00\",\"author\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\"},\"description\":\"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...\",\"breadcrumb\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png\",\"contentUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png\",\"width\":700,\"height\":366},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/cristozzo.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cabelos X Dieta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/\",\"name\":\"Cris Tozzo Nutricionista Blog\",\"description\":\"Cris Tozzo Nutricionista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\",\"name\":\"conteudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"caption\":\"conteudo\"},\"sameAs\":[\"http:\/\/www.cristozzo.com.br\",\"https:\/\/www.facebook.com\/cristozzonutri\",\"https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri\"],\"url\":\"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cabelos X Dieta! - Cris Tozzo Nutricionista Blog","description":"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Cabelos X Dieta! - Cris Tozzo Nutricionista Blog","og_description":"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...","og_url":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/","og_site_name":"Cris Tozzo Nutricionista Blog","article_author":"https:\/\/www.facebook.com\/cristozzonutri","article_published_time":"2015-11-18T11:56:06+00:00","article_modified_time":"2016-12-12T18:08:04+00:00","og_image":[{"width":700,"height":366,"url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png","type":"image\/png"}],"author":"conteudo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/cristozzonutri","twitter_misc":{"Escrito por":"conteudo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/","url":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/","name":"Cabelos X Dieta! - Cris Tozzo Nutricionista Blog","isPartOf":{"@id":"http:\/\/cristozzo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage"},"image":{"@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage"},"thumbnailUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png","datePublished":"2015-11-18T11:56:06+00:00","dateModified":"2016-12-12T18:08:04+00:00","author":{"@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a"},"description":"Cabelos x Dieta! Quanto dinheiro j\u00e1 gastamos para deixar nossos cabelos lindos? Eis um ponto cr\u00edtico da nossa vaidade, queremos fios brilhantes...","breadcrumb":{"@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#primaryimage","url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png","contentUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/11\/Nutri\u00e7\u00e3o-para-cabelos-lindos.png","width":700,"height":366},{"@type":"BreadcrumbList","@id":"http:\/\/cristozzo.com.br\/blog\/cabelos-vs-dieta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/cristozzo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cabelos X Dieta!"}]},{"@type":"WebSite","@id":"http:\/\/cristozzo.com.br\/blog\/#website","url":"http:\/\/cristozzo.com.br\/blog\/","name":"Cris Tozzo Nutricionista Blog","description":"Cris Tozzo Nutricionista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a","name":"conteudo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","caption":"conteudo"},"sameAs":["http:\/\/www.cristozzo.com.br","https:\/\/www.facebook.com\/cristozzonutri","https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri"],"url":"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/"}]}},"_links":{"self":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=682"}],"version-history":[{"count":7,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/682\/revisions"}],"predecessor-version":[{"id":1262,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/682\/revisions\/1262"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media\/683"}],"wp:attachment":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=682"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}