{"id":121,"date":"2015-08-21T13:29:01","date_gmt":"2015-08-21T13:29:01","guid":{"rendered":"http:\/\/cristozzo.com.br\/blog\/?p=121"},"modified":"2015-09-18T21:19:51","modified_gmt":"2015-09-18T21:19:51","slug":"alimentostermogenicos","status":"publish","type":"post","link":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/","title":{"rendered":"Alimentos termog\u00eanicos"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/alimentos-termogenicos.png\" alt=\"alimentos termogenicos\" width=\"700\" height=\"366\" \/><\/p>\n<p>Voc&ecirc; j&aacute; deve ter ouvido falar nos <strong>alimentos termog&ecirc;nicos<\/strong>. Eles ficaram bem conhecidos por ajudarem a queimar calorias. E como eles fazem isso? <!--more-->Esses alimentos aumentam a temperatura corporal, estimulando o metabolismo e ajudando no processo de emagrecimento.<\/p>\n<p>Mas al&eacute;m disso os <strong>alimentos termog&ecirc;nicos<\/strong> tamb&eacute;m contribuem para o ganho muscular e um melhor desempenho na pr&aacute;tica de atividades f&iacute;sicas.<\/p>\n<p>Confira alguns alimentos termog&ecirc;nicos:<\/p>\n<p><strong>GENGIBRE<\/strong>&nbsp;&ndash; acelera o metabolismo em at&eacute; 20%! Tamb&eacute;m ajuda a digest&atilde;o e previne o envelhecimento precoce. <span class=\"text_exposed_show\"><br>\nCanela &ndash; facilita a digest&atilde;o e tem a&ccedil;&atilde;o estimulante. Pode ser consumida em p&oacute; ou na forma de ch&aacute;.<\/span><\/p>\n<p><span class=\"text_exposed_show\"><strong>CAF&Eacute;<\/strong> &ndash; ajuda a ficar em estado de alerta e diminui a fadiga. &Oacute;timo para quem tem pregui&ccedil;a de praticar exerc&iacute;cios.<br>\n<\/span><\/p>\n<p><span class=\"text_exposed_show\"><strong>PIMENTA VERMELHA<\/strong> &ndash; cont&eacute;m capsaicina, aumenta a quebra de gordura e o gasto cal&oacute;rico ap&oacute;s as refei&ccedil;&otilde;es, al&eacute;m de ajudar a varrer a gordura das art&eacute;rias.<\/span><\/p>\n<p><span class=\"text_exposed_show\"><strong>CH&Aacute; VERDE<\/strong> &ndash; cont&eacute;m subst&acirc;ncias como a cafe&iacute;na e as catequinas, obrigam o organismo a buscar energia nas reservas de gordura, ajudando a queimar calorias, Ainda desintoxica e combate a reten&ccedil;&atilde;o de l&iacute;quidos.<\/span><\/p>\n<p><span class=\"text_exposed_show\"><strong>CH&Aacute; DE HIBISCO<\/strong> &ndash; estimula a queima de gordura corporal, facilita a digest&atilde;o e combate a reten&ccedil;&atilde;o de l&iacute;quidos.<\/span><\/p>\n<p><strong>&Oacute;LEO DE COCO<\/strong> &nbsp;&ndash; a melhor gordura para utilizar no cozimento. &Eacute; rido em gorduras saturadas do tipo triglicer&iacute;deos de cadeia m&eacute;dia (TCM), facilmente digeridos, absorvidos e transformados em energia para o organismo, auxiliando assim, no emagrecimento. O &oacute;leo de coco tamb&eacute;m &eacute; rido em &aacute;cido l&aacute;urico, que contribui com a sa&uacute;de cardiovascular e tamb&eacute;m fortalece o sistema imunol&oacute;gico. Al&eacute;m disso tamb&eacute;m &eacute; um poderoso antioxidante natural.<\/p>\n<p><strong>CANELA<\/strong> <i class=\"_4-k1 img sp_UkKp2mjPS47 sx_cd1c67\">&ndash; <\/i>aumenta o metabolismo basar e possui alto teor de c&aacute;lcio mineral. Procure polvilhar em cima de frutas e misturar em bebidas quentes como leite, caf&eacute; e ch&aacute;. A canela al&eacute;m de contribuir para o emagrecimento, tamb&eacute;m d&aacute; um sabor delicioso.<\/p>\n<p><strong>PIMENTA VERMELHA<\/strong> &ndash; &eacute; rica em capsaicina, subst&acirc;ncia que ajuda na quebra de gorduras do tecido adiposo. Ingerindo cerca de tr&ecirc;s gramas ao dia, voc&ecirc; aumenta em at&eacute; 20% a atividade metab&oacute;lica. Adicione a pimenta vermelha em salada e pratos quentes, evitando o consumo noturno pois pode atrapalhar a qualidade do sono.<\/p>\n<p><span class=\"text_exposed_show\"><strong>&Aacute;GUA GELADA<\/strong> &ndash; o organismo gasta mais energia para conseguir equilibrar a temperatura.<\/span><\/p>\n<p>Mas cuidado, evite o consumo excessivo dos <strong>alimentos termog&ecirc;nicos<\/strong>, pois podem causar o aumento da press&atilde;o e dores de cabe&ccedil;a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/09\/nutridica_icones.png\" alt=\"nutridica_icones\" width=\"231\" height=\"60\" \/><\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>Voc&ecirc; j&aacute; deve ter ouvido falar nos alimentos termog&ecirc;nicos. Eles ficaram bem conhecidos por ajudarem a queimar calorias. E como eles fazem isso?<\/p>\n","protected":false},"author":2,"featured_media":173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,5],"tags":[54,44,49,55,51,50,42,47,48,52,53,46,45],"class_list":["post-121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-destaque","tag-agua-gelada","tag-alimentos-termogenicos","tag-cafe","tag-canela","tag-cha-de-hibisco","tag-cha-verde","tag-emagrecimento","tag-estimulante","tag-metabolismo","tag-oleo-de-coco","tag-pimenta-vermelha","tag-queima-calorica","tag-termogenicos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog<\/title>\n<meta name=\"description\" content=\"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"og:description\" content=\"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristozzonutri\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-21T13:29:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-18T21:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"conteudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/cristozzonutri\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conteudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/\",\"name\":\"Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog\",\"isPartOf\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png\",\"datePublished\":\"2015-08-21T13:29:01+00:00\",\"dateModified\":\"2015-09-18T21:19:51+00:00\",\"author\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\"},\"description\":\"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.\",\"breadcrumb\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png\",\"contentUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png\",\"width\":700,\"height\":700,\"caption\":\"termogenicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/cristozzo.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alimentos termog\u00eanicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/\",\"name\":\"Cris Tozzo Nutricionista Blog\",\"description\":\"Cris Tozzo Nutricionista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\",\"name\":\"conteudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"caption\":\"conteudo\"},\"sameAs\":[\"http:\/\/www.cristozzo.com.br\",\"https:\/\/www.facebook.com\/cristozzonutri\",\"https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri\"],\"url\":\"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog","description":"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog","og_description":"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.","og_url":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/","og_site_name":"Cris Tozzo Nutricionista Blog","article_author":"https:\/\/www.facebook.com\/cristozzonutri","article_published_time":"2015-08-21T13:29:01+00:00","article_modified_time":"2015-09-18T21:19:51+00:00","og_image":[{"width":700,"height":700,"url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png","type":"image\/png"}],"author":"conteudo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/cristozzonutri","twitter_misc":{"Escrito por":"conteudo","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/","url":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/","name":"Alimentos termog\u00eanicos - Cris Tozzo Nutricionista Blog","isPartOf":{"@id":"http:\/\/cristozzo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage"},"image":{"@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage"},"thumbnailUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png","datePublished":"2015-08-21T13:29:01+00:00","dateModified":"2015-09-18T21:19:51+00:00","author":{"@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a"},"description":"Os alimentos termog\u00eanicos ajudam a queimar calorias atrav\u00e9s do aumento da temperatura corporal.","breadcrumb":{"@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#primaryimage","url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png","contentUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2015\/08\/termogenicos.png","width":700,"height":700,"caption":"termogenicos"},{"@type":"BreadcrumbList","@id":"http:\/\/cristozzo.com.br\/blog\/alimentostermogenicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/cristozzo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Alimentos termog\u00eanicos"}]},{"@type":"WebSite","@id":"http:\/\/cristozzo.com.br\/blog\/#website","url":"http:\/\/cristozzo.com.br\/blog\/","name":"Cris Tozzo Nutricionista Blog","description":"Cris Tozzo Nutricionista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a","name":"conteudo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","caption":"conteudo"},"sameAs":["http:\/\/www.cristozzo.com.br","https:\/\/www.facebook.com\/cristozzonutri","https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri"],"url":"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/"}]}},"_links":{"self":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=121"}],"version-history":[{"count":5,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/121\/revisions"}],"predecessor-version":[{"id":435,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/121\/revisions\/435"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media\/173"}],"wp:attachment":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=121"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}