{"id":1082,"date":"2016-08-02T13:13:26","date_gmt":"2016-08-02T13:13:26","guid":{"rendered":"http:\/\/cristozzo.com.br\/blog\/?p=1082"},"modified":"2018-02-13T23:19:03","modified_gmt":"2018-02-13T23:19:03","slug":"curso-beneficente","status":"publish","type":"post","link":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/","title":{"rendered":"Curso Beneficente Florian\u00f3polis &#8211; 11\/08 \/2016"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><a href=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\"><img loading=\"lazy\" decoding=\"async\" class=\"img-responsive wow fadeIn animated\" src=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\" alt=\"curso\" width=\"700\" height=\"700\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Nesse m&ecirc;s de agosto, vamos encher os idosos de alegria? Ano passado foi a vez das crian&ccedil;as e nesse ano nosso Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar carente aqui da Grande Florian&oacute;polis! Chegou a vez de enchermos de amor nossos queridos velhinhos! A ideia &eacute; simples: preparei um curso super legal de culin&aacute;ria saud&aacute;vel para voc&ecirc;s e em troca queremos arrecadar pequenas coisas que fazem muita diferen&ccedil;a!<\/p>\n<p>As inscri&ccedil;&otilde;es para participar ser&atilde;o roupa<span class=\"text_exposed_show\">s novas ou em bom estado para aquecer nossos velhinhos e seus cora&ccedil;&otilde;es! Fraldas geri&aacute;tricas tamb&eacute;m valem! No curso, vou ensinar a voc&ecirc;s receitas funcionais, <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/semgluten?source=feed_text&amp;story_id=1070624406307889\" data-ft='{\"tn\":\"*N\",\"type\":104}'><span class=\"_58cl\">&#8234;#&lrm;<\/span><span class=\"_58cm\">semgluten&#8236;<\/span><\/a>,<a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/semleite?source=feed_text&amp;story_id=1070624406307889\" data-ft='{\"tn\":\"*N\",\"type\":104}'><span class=\"_58cl\">&#8234;#&lrm;<\/span><span class=\"_58cm\">semleite&#8236;<\/span><\/a> e cheias de sa&uacute;de! Vamos apreender como montar uma lancheira equilibrada para carregar por a&iacute;, seja para adultos ou crian&ccedil;as, j&aacute; que muitos fazem as suas pr&oacute;prias marmitas! As vagas s&atilde;o limitadas e ano passado fecharam rapidinho, espero contar com voc&ecirc;s nessa corrente esse ano tamb&eacute;m! <i class=\"_3kkw\"><span class=\"accessible_elem\">&#128591;<\/span><\/i> As vagas ser&atilde;o preenchidas por ordem de inscri&ccedil;&atilde;o via e-mail!<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>Onde: Angeloni Capoeiras<br>\nData: 11\/08\/2016<br>\nHor&aacute;rio: 19h30min<\/p>\n<p>Valor: Uma roupa em &oacute;timo estado ou fraldas geri&aacute;tricas<\/p>\n<p>Informa&ccedil;&otilde;es e inscri&ccedil;&otilde;es pelo e-mail: cursos@cristozzo.com.br<\/p>\n<p>Espero voc&ecirc;s l&aacute;!!!<\/p>\n<\/div>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nesse m&ecirc;s de agosto, vamos encher os idosos de alegria? Ano passado foi a vez das crian&ccedil;as e nesse ano nosso Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar carente aqui da Grande Florian&oacute;polis! Chegou a vez de enchermos de amor nossos queridos velhinhos! A ideia &eacute; simples: preparei [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,4],"tags":[265],"class_list":["post-1082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-eventos","tag-curso-cursoculinaria-lancheirasaudavel-beneficente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso Beneficente Lancheira Saud\u00e1vel<\/title>\n<meta name=\"description\" content=\"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso Beneficente Lancheira Saud\u00e1vel\" \/>\n<meta property=\"og:description\" content=\"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!\" \/>\n<meta property=\"og:url\" content=\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/\" \/>\n<meta property=\"og:site_name\" content=\"Cris Tozzo Nutricionista Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/cristozzonutri\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-02T13:13:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-13T23:19:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"conteudo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/cristozzonutri\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"conteudo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/\",\"name\":\"Curso Beneficente Lancheira Saud\u00e1vel\",\"isPartOf\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\",\"datePublished\":\"2016-08-02T13:13:26+00:00\",\"dateModified\":\"2018-02-13T23:19:03+00:00\",\"author\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\"},\"description\":\"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!\",\"breadcrumb\":{\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\",\"contentUrl\":\"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/cristozzo.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso Beneficente Florian\u00f3polis &#8211; 11\/08 \/2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#website\",\"url\":\"http:\/\/cristozzo.com.br\/blog\/\",\"name\":\"Cris Tozzo Nutricionista Blog\",\"description\":\"Cris Tozzo Nutricionista\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a\",\"name\":\"conteudo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g\",\"caption\":\"conteudo\"},\"sameAs\":[\"http:\/\/www.cristozzo.com.br\",\"https:\/\/www.facebook.com\/cristozzonutri\",\"https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri\"],\"url\":\"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso Beneficente Lancheira Saud\u00e1vel","description":"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Curso Beneficente Lancheira Saud\u00e1vel","og_description":"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!","og_url":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/","og_site_name":"Cris Tozzo Nutricionista Blog","article_author":"https:\/\/www.facebook.com\/cristozzonutri","article_published_time":"2016-08-02T13:13:26+00:00","article_modified_time":"2018-02-13T23:19:03+00:00","og_image":[{"width":700,"height":700,"url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png","type":"image\/png"}],"author":"conteudo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/cristozzonutri","twitter_misc":{"Written by":"conteudo","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/","url":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/","name":"Curso Beneficente Lancheira Saud\u00e1vel","isPartOf":{"@id":"http:\/\/cristozzo.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage"},"image":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage"},"thumbnailUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png","datePublished":"2016-08-02T13:13:26+00:00","dateModified":"2018-02-13T23:19:03+00:00","author":{"@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a"},"description":"Vamos encher os idosos de alegria? Nesse ano o Curso Beneficente tem o objetivo de arrecadar roupas para idosos de uma Lar de Florian\u00f3polis!","breadcrumb":{"@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#primaryimage","url":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png","contentUrl":"http:\/\/cristozzo.com.br\/blog\/wp-content\/uploads\/2016\/08\/curso.png","width":700,"height":700},{"@type":"BreadcrumbList","@id":"http:\/\/cristozzo.com.br\/blog\/curso-beneficente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/cristozzo.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Curso Beneficente Florian\u00f3polis &#8211; 11\/08 \/2016"}]},{"@type":"WebSite","@id":"http:\/\/cristozzo.com.br\/blog\/#website","url":"http:\/\/cristozzo.com.br\/blog\/","name":"Cris Tozzo Nutricionista Blog","description":"Cris Tozzo Nutricionista","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/cristozzo.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/6c2ead489048142a075f2b4550a4a00a","name":"conteudo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/cristozzo.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46d77cd17290c5ba7e690bf8dff551bbbcdbe7b48d29afd92164dd472011262?s=96&d=mm&r=g","caption":"conteudo"},"sameAs":["http:\/\/www.cristozzo.com.br","https:\/\/www.facebook.com\/cristozzonutri","https:\/\/x.com\/https:\/\/twitter.com\/cristozzonutri"],"url":"http:\/\/cristozzo.com.br\/blog\/author\/conteudo\/"}]}},"_links":{"self":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":3,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"predecessor-version":[{"id":1343,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/posts\/1082\/revisions\/1343"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media\/1083"}],"wp:attachment":[{"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cristozzo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}